{"id":2956,"date":"2014-06-14T20:34:42","date_gmt":"2014-06-15T01:34:42","guid":{"rendered":"http:\/\/meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619.jpg"},"modified":"2014-06-14T20:34:42","modified_gmt":"2014-06-15T01:34:42","slug":"img_2619","status":"inherit","type":"attachment","link":"https:\/\/www.meisterplanet.com\/journal\/img_2619\/","title":{"rendered":"Duck Tape Festival &#8211; Alien"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-2956","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"337\" src=\"https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619-450x337.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619-450x337.jpg 450w, https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 450px) 85vw, 450px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3264,"height":2448,"file":"2014\/06\/IMG_2619.jpg","sizes":{"thumbnail":{"file":"IMG_2619-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619-150x150.jpg"},"medium":{"file":"IMG_2619-450x337.jpg","width":450,"height":337,"mime_type":"image\/jpeg","source_url":"https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619-450x337.jpg"},"large":{"file":"IMG_2619-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619-1024x768.jpg"},"post-thumbnail":{"file":"IMG_2619-940x198.jpg","width":940,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619-940x198.jpg"},"full":{"file":"IMG_2619.jpg","width":3264,"height":2448,"mime_type":"image\/jpeg","source_url":"https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619.jpg"}},"image_meta":{"aperture":2.2,"credit":"","camera":"iPhone 5s","caption":"","created_timestamp":1402752278,"copyright":"","focal_length":"4.12","iso":"32","shutter_speed":"0.00068212824010914","title":""}},"post":null,"source_url":"https:\/\/www.meisterplanet.com\/journal\/wp-content\/uploads\/2014\/06\/IMG_2619.jpg","_links":{"self":[{"href":"https:\/\/www.meisterplanet.com\/journal\/wp-json\/wp\/v2\/media\/2956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.meisterplanet.com\/journal\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.meisterplanet.com\/journal\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.meisterplanet.com\/journal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.meisterplanet.com\/journal\/wp-json\/wp\/v2\/comments?post=2956"}]}}